{"id":4357,"date":"2021-01-01T07:00:00","date_gmt":"2021-01-01T07:00:00","guid":{"rendered":"https:\/\/arte351.pt\/art\/?p=4357"},"modified":"2021-01-03T13:33:40","modified_gmt":"2021-01-03T13:33:40","slug":"morre-aos-98-anos-o-estilista-frances-pierre-cardin","status":"publish","type":"post","link":"https:\/\/arte351.pt\/art\/2021\/01\/01\/morre-aos-98-anos-o-estilista-frances-pierre-cardin\/","title":{"rendered":"Morre aos 98 anos o estilista franc\u00eas Pierre Cardin"},"content":{"rendered":"<h2>Conheci e convivi com o inigual\u00e1vel Pierre Cardin.<\/h2>\n<p style=\"text-align: justify;\">Eu tive o prazer de conviver com este Mestre da moda. Um g\u00eanio que abriu a porta para v\u00e1rios artistas e foi mecenas de muitos, entre eles o meu amigo artista Marcos Marin. Apaixonado pela arte, <strong>Pierre Cardin<\/strong> \u00e9 um dos patronos da Bienal de Veneza.<\/p>\n<figure id=\"attachment_4367\" class=\"thumbnail wp-caption alignright\" style=\"width: 261px\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-4367 size-medium\" src=\"https:\/\/arte351.pt\/art\/wp-content\/uploads\/2021\/01\/pierre-cardin-001-251x300.jpg\" alt=\"\" width=\"251\" height=\"300\" srcset=\"https:\/\/arte351.pt\/art\/wp-content\/uploads\/2021\/01\/pierre-cardin-001-251x300.jpg 251w, https:\/\/arte351.pt\/art\/wp-content\/uploads\/2021\/01\/pierre-cardin-001.jpg 569w\" sizes=\"(max-width: 251px) 100vw, 251px\" \/><figcaption class=\"caption wp-caption-text\">Renato Rodyner e Pierre Cardin<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Conheci Pierre Cardin em Lacoste, cidade francesa, em seu Castelo que pertenceu ao Marqu\u00eas de Sade. Foi Marcos Marin que me apresentou a ele. Sinto-me lisonjeado ao recordar aqueles momentos, de lembrar que <strong>um quadro meu est\u00e1 pendurado em uma das paredes do castelo de Cardin<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Com a simplicidade das pessoas nobres de esp\u00edrito, Pierre Cardin sempre foi sol\u00edcito e gentil, inclusive me convidou a ficar hospedado em sua casa em Lacoste. Nesta visita fui levado a jantares regados a vinhos excepcionais e com o melhor da gastronomia francesa. Em outras ocasi\u00f5es fomos a bailes em Paris. Sempre anal\u00edtico e atualizado com o que acontecia no mundo da arte, tivemos diversas conversas que me engrandeceram de conhecimento e sensibilidade. Sinto-me triste pela sua partida, mas trago em mim a gratid\u00e3o de t\u00ea-lo conhecido e de ser um dos artistas a vigorar em sua colec\u00e7\u00e3o de Arte.<\/p>\n<p>Pierre Cardin eternizou seu estilo futurista e design inspirado na Era Espacial. Um dos \u00faltimos vultos da Alta-Custara europeia e percursor do pronto-a- vestir na adolesc\u00eancia, aos 14 nos deu os primeiros passos numa alfaiataria em Sanint-\u00c9tienne. Em Parais, viria a trabalhar em 1944 com Madame Paquin- onde desenhou os figurinos e mascaras do filme A Bela e A fera(1946),de Jean Cocteau- passaria tamb\u00e9m pelo ateli\u00ea da italiana Elsa Schiaparellie tornar-se-ia chefe do ateli\u00ea dos alfaiates de Cristian Dior, em 1947.<\/p>\n<p>[masterslider id=&#8221;2&#8243;]<\/p>\n<p style=\"text-align: justify;\">Criou em 1950 sua pr\u00f3pria marca (Pierre Cardin) e revolucionou o mundo da moda foi um dos primeiros a pensar no conceito unis-sexo, assim como na pr\u00f3pria ideia de pronto-a-vestir. fez uma primeira colec\u00e7\u00e3o em 1959 .<\/p>\n<p style=\"text-align: justify;\">Pioneiro, foi o primeiro criador de moda a desenhar uma colec\u00e7\u00e3o masculina, em 1960. Dois anos depois desenhou outra colec\u00e7\u00e3o para ser vendida em armaz\u00e9ns Printemps causando esc\u00e2ndalo que lhe valeu a expuls\u00e3o da Chambre Syndicale de la Hayte Couture,a confedera\u00e7\u00e3o de criadores da alta costura ( o que todos acabaram fazendo depois dele) em 1966 foi readmitido, tendo mais tarde chegado \u00e0 presid\u00eancia daquela estrutura.<\/p>\n<p style=\"text-align: justify;\">Tem muito do que falar deste g\u00e9nio da arte que deixa marcas de sua passada pela terra. N\u00e3o teve medo, tamb\u00e9m, de se aventurar noutros mercados que n\u00e3o o europeu. Chegou \u00e0 China em 1978 e abriu um showroom em Pequim em 1981 \u2014 em 2018 fez uma enorme passagem de modelos, para assinalar os seus 40 anos naquele pa\u00eds, com a Muralha da China como cen\u00e1rio. Em 1986 desfilou na Pra\u00e7a Vermelha, em Moscovo, no ano seguinte abriu uma loja na mesma cidade. A \u00faltima loja de luxo que inaugurou foi em 2017, em Paris, na Rue Royale.<\/p>\n<p style=\"text-align: justify;\">Segundo o Le Figaro, Pierre Cardin detinha \u00e0 data da sua morte mais de 850 licen\u00e7as de produtos e 500 f\u00e1bricas, empregando cerca de 200 mil pessoas directa ou indirectamente em todo o mundo. Orgulhou-se sempre do seu percurso feito a pulso de filho de migrantes pobres (eram sete irm\u00e3os) que singrou num mundo de luxo e esplendor. Em 2017, para uma exposi\u00e7\u00e3o sobre a imigra\u00e7\u00e3o italiana no Museu da Imigra\u00e7\u00e3o, em Paris, intitulada Ciao Italia! \u2014 que contemplava outros famosos como os actores Yves Montand (1921-1991) ou Serge Reggiani (1922-2004) \u2014, o criador declarou: \u201cEu sou o meu maior sucesso. Sou uma crian\u00e7a do sub\u00farbio e tornei-me Pierre Cardin. Se tivesse de recome\u00e7ar, voltaria a faz\u00ea-lo com muito entusiasmo.\u201d<\/p>\n<p style=\"text-align: justify;\">Aqui fica meu testemunho de Gratid\u00e3o por apoiar-me, bem como muitos artistas brasileiros das artes pl\u00e1sticas, musica e cinema. H\u00e1 muito que falar deste g\u00e9nio e de sua vis\u00e3o do futuro que deixou para sempre sua marca na passagem por este plano de vida. Pierre Cardin amava a vida e a arte, em seus 98 anos, quase um s\u00e9culo de vida, ele mostrou talento e inova\u00e7\u00e3o que o levaram ao topo do mundo da moda. Nascido a 2 de Julho de 1922, em Veneza, na It\u00e1lia. Oriundo de uma fam\u00edlia de agricultores que foram procurar melhor vida em Fran\u00e7a. Chegou ao mundo como Pietro e se despediu como Pierre Cardin, uma das maiores marcas da hist\u00f3ria da moda.<\/p>\n<p><a href=\"https:\/\/arte351.pt\/art\/category\/colunistas-2\/renato-rodyner\/\"><img decoding=\"async\" class=\"alignleft wp-image-397\" src=\"https:\/\/arte351.pt\/art\/wp-content\/uploads\/2016\/03\/avatar_renato_rodyner-150x150.jpg\" alt=\"\" width=\"80\" height=\"80\" srcset=\"https:\/\/arte351.pt\/art\/wp-content\/uploads\/2016\/03\/avatar_renato_rodyner-150x150.jpg 150w, https:\/\/arte351.pt\/art\/wp-content\/uploads\/2016\/03\/avatar_renato_rodyner-300x300.jpg 300w, https:\/\/arte351.pt\/art\/wp-content\/uploads\/2016\/03\/avatar_renato_rodyner.jpg 600w\" sizes=\"(max-width: 80px) 100vw, 80px\" \/><\/a><\/p>\n<h5><em><a href=\"https:\/\/arte351.pt\/art\/category\/colunistas-2\/renato-rodyner\/\">Coluna &#8211;&nbsp;Renato Rodyner<\/a><\/em><\/h5>\n<h5><em>Renato Rodyner, brasileiro, Porto Alegre, RS, Brasil, 1962. Artista pl\u00e1stico, Jornalista, Curador e Cr\u00edtico de Arte, propriet\u00e1rio&nbsp;da Rodyner Gallery e Editor Geral da &#8220;Arte351 Magazine&#8221;.<\/em><\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Conheci e convivi com o inigual\u00e1vel Pierre Cardin. Eu tive o prazer de conviver com este Mestre da moda. Um g\u00eanio que abriu a porta para v\u00e1rios artistas e foi [&hellip;]<\/p>\n","protected":false},"author":34415,"featured_media":4364,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-4357","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-art-contemp"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Morre aos 98 anos o estilista franc\u00eas Pierre Cardin<\/title>\n<meta name=\"description\" content=\"Sinto-me lisonjeado ao recordar aqueles momentos, de lembrar que um quadro meu est\u00e1 pendurado em uma das paredes do castelo de Pierre Cardin.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arte351.pt\/art\/2021\/01\/01\/morre-aos-98-anos-o-estilista-frances-pierre-cardin\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Morre aos 98 anos o estilista franc\u00eas Pierre Cardin\" \/>\n<meta property=\"og:description\" content=\"Sinto-me lisonjeado ao recordar aqueles momentos, de lembrar que um quadro meu est\u00e1 pendurado em uma das paredes do castelo de Pierre Cardin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arte351.pt\/art\/2021\/01\/01\/morre-aos-98-anos-o-estilista-frances-pierre-cardin\/\" \/>\n<meta property=\"og:site_name\" content=\"Arte351 - Art Magazine Portugal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/arte351magazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-01T07:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-03T13:33:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arte351.pt\/art\/wp-content\/uploads\/2021\/01\/arte351-2020-pierre-cardin.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"578\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipa Arte 351\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipa Arte 351\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/arte351.pt\\\/art\\\/2021\\\/01\\\/01\\\/morre-aos-98-anos-o-estilista-frances-pierre-cardin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arte351.pt\\\/art\\\/2021\\\/01\\\/01\\\/morre-aos-98-anos-o-estilista-frances-pierre-cardin\\\/\"},\"author\":{\"name\":\"Equipa Arte 351\",\"@id\":\"https:\\\/\\\/arte351.pt\\\/art\\\/#\\\/schema\\\/person\\\/1d081d5dbc7c2a3f2317da95c823a5bd\"},\"headline\":\"Morre aos 98 anos o estilista franc\u00eas Pierre Cardin\",\"datePublished\":\"2021-01-01T07:00:00+00:00\",\"dateModified\":\"2021-01-03T13:33:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/arte351.pt\\\/art\\\/2021\\\/01\\\/01\\\/morre-aos-98-anos-o-estilista-frances-pierre-cardin\\\/\"},\"wordCount\":802,\"publisher\":{\"@id\":\"https:\\\/\\\/arte351.pt\\\/art\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/arte351.pt\\\/art\\\/2021\\\/01\\\/01\\\/morre-aos-98-anos-o-estilista-frances-pierre-cardin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arte351.pt\\\/art\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/arte351-2020-pierre-cardin.jpg\",\"articleSection\":[\"Arte\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arte351.pt\\\/art\\\/2021\\\/01\\\/01\\\/morre-aos-98-anos-o-estilista-frances-pierre-cardin\\\/\",\"url\":\"https:\\\/\\\/arte351.pt\\\/art\\\/2021\\\/01\\\/01\\\/morre-aos-98-anos-o-estilista-frances-pierre-cardin\\\/\",\"name\":\"Morre aos 98 anos o estilista franc\u00eas Pierre Cardin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arte351.pt\\\/art\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/arte351.pt\\\/art\\\/2021\\\/01\\\/01\\\/morre-aos-98-anos-o-estilista-frances-pierre-cardin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/arte351.pt\\\/art\\\/2021\\\/01\\\/01\\\/morre-aos-98-anos-o-estilista-frances-pierre-cardin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arte351.pt\\\/art\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/arte351-2020-pierre-cardin.jpg\",\"datePublished\":\"2021-01-01T07:00:00+00:00\",\"dateModified\":\"2021-01-03T13:33:40+00:00\",\"description\":\"Sinto-me lisonjeado ao recordar aqueles momentos, de lembrar que um quadro meu est\u00e1 pendurado em uma das paredes do castelo de Pierre Cardin.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arte351.pt\\\/art\\\/2021\\\/01\\\/01\\\/morre-aos-98-anos-o-estilista-frances-pierre-cardin\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arte351.pt\\\/art\\\/2021\\\/01\\\/01\\\/morre-aos-98-anos-o-estilista-frances-pierre-cardin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/arte351.pt\\\/art\\\/2021\\\/01\\\/01\\\/morre-aos-98-anos-o-estilista-frances-pierre-cardin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/arte351.pt\\\/art\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/arte351-2020-pierre-cardin.jpg\",\"contentUrl\":\"https:\\\/\\\/arte351.pt\\\/art\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/arte351-2020-pierre-cardin.jpg\",\"width\":1200,\"height\":578},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arte351.pt\\\/art\\\/2021\\\/01\\\/01\\\/morre-aos-98-anos-o-estilista-frances-pierre-cardin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/arte351.pt\\\/art\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Morre aos 98 anos o estilista franc\u00eas Pierre Cardin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arte351.pt\\\/art\\\/#website\",\"url\":\"https:\\\/\\\/arte351.pt\\\/art\\\/\",\"name\":\"Arte351 - Art Magazine Portugal\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/arte351.pt\\\/art\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arte351.pt\\\/art\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/arte351.pt\\\/art\\\/#organization\",\"name\":\"Arte351 - Art Magazine Portugal\",\"url\":\"https:\\\/\\\/arte351.pt\\\/art\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/arte351.pt\\\/art\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/arte351.pt\\\/art\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/cropped-logo-arte351-color.png\",\"contentUrl\":\"https:\\\/\\\/arte351.pt\\\/art\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/cropped-logo-arte351-color.png\",\"width\":514,\"height\":200,\"caption\":\"Arte351 - Art Magazine Portugal\"},\"image\":{\"@id\":\"https:\\\/\\\/arte351.pt\\\/art\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/arte351magazine\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/arte351.pt\\\/art\\\/#\\\/schema\\\/person\\\/1d081d5dbc7c2a3f2317da95c823a5bd\",\"name\":\"Equipa Arte 351\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3f97e62c832ede8fafe5d2f9e31f8a055e187b6b31056d1e065d95e034db52e2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3f97e62c832ede8fafe5d2f9e31f8a055e187b6b31056d1e065d95e034db52e2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3f97e62c832ede8fafe5d2f9e31f8a055e187b6b31056d1e065d95e034db52e2?s=96&d=mm&r=g\",\"caption\":\"Equipa Arte 351\"},\"url\":\"https:\\\/\\\/arte351.pt\\\/art\\\/author\\\/admin2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Morre aos 98 anos o estilista franc\u00eas Pierre Cardin","description":"Sinto-me lisonjeado ao recordar aqueles momentos, de lembrar que um quadro meu est\u00e1 pendurado em uma das paredes do castelo de Pierre Cardin.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arte351.pt\/art\/2021\/01\/01\/morre-aos-98-anos-o-estilista-frances-pierre-cardin\/","og_locale":"pt_BR","og_type":"article","og_title":"Morre aos 98 anos o estilista franc\u00eas Pierre Cardin","og_description":"Sinto-me lisonjeado ao recordar aqueles momentos, de lembrar que um quadro meu est\u00e1 pendurado em uma das paredes do castelo de Pierre Cardin.","og_url":"https:\/\/arte351.pt\/art\/2021\/01\/01\/morre-aos-98-anos-o-estilista-frances-pierre-cardin\/","og_site_name":"Arte351 - Art Magazine Portugal","article_publisher":"https:\/\/www.facebook.com\/arte351magazine\/","article_published_time":"2021-01-01T07:00:00+00:00","article_modified_time":"2021-01-03T13:33:40+00:00","og_image":[{"width":1200,"height":578,"url":"https:\/\/arte351.pt\/art\/wp-content\/uploads\/2021\/01\/arte351-2020-pierre-cardin.jpg","type":"image\/jpeg"}],"author":"Equipa Arte 351","twitter_misc":{"Escrito por":"Equipa Arte 351","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/arte351.pt\/art\/2021\/01\/01\/morre-aos-98-anos-o-estilista-frances-pierre-cardin\/#article","isPartOf":{"@id":"https:\/\/arte351.pt\/art\/2021\/01\/01\/morre-aos-98-anos-o-estilista-frances-pierre-cardin\/"},"author":{"name":"Equipa Arte 351","@id":"https:\/\/arte351.pt\/art\/#\/schema\/person\/1d081d5dbc7c2a3f2317da95c823a5bd"},"headline":"Morre aos 98 anos o estilista franc\u00eas Pierre Cardin","datePublished":"2021-01-01T07:00:00+00:00","dateModified":"2021-01-03T13:33:40+00:00","mainEntityOfPage":{"@id":"https:\/\/arte351.pt\/art\/2021\/01\/01\/morre-aos-98-anos-o-estilista-frances-pierre-cardin\/"},"wordCount":802,"publisher":{"@id":"https:\/\/arte351.pt\/art\/#organization"},"image":{"@id":"https:\/\/arte351.pt\/art\/2021\/01\/01\/morre-aos-98-anos-o-estilista-frances-pierre-cardin\/#primaryimage"},"thumbnailUrl":"https:\/\/arte351.pt\/art\/wp-content\/uploads\/2021\/01\/arte351-2020-pierre-cardin.jpg","articleSection":["Arte"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/arte351.pt\/art\/2021\/01\/01\/morre-aos-98-anos-o-estilista-frances-pierre-cardin\/","url":"https:\/\/arte351.pt\/art\/2021\/01\/01\/morre-aos-98-anos-o-estilista-frances-pierre-cardin\/","name":"Morre aos 98 anos o estilista franc\u00eas Pierre Cardin","isPartOf":{"@id":"https:\/\/arte351.pt\/art\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arte351.pt\/art\/2021\/01\/01\/morre-aos-98-anos-o-estilista-frances-pierre-cardin\/#primaryimage"},"image":{"@id":"https:\/\/arte351.pt\/art\/2021\/01\/01\/morre-aos-98-anos-o-estilista-frances-pierre-cardin\/#primaryimage"},"thumbnailUrl":"https:\/\/arte351.pt\/art\/wp-content\/uploads\/2021\/01\/arte351-2020-pierre-cardin.jpg","datePublished":"2021-01-01T07:00:00+00:00","dateModified":"2021-01-03T13:33:40+00:00","description":"Sinto-me lisonjeado ao recordar aqueles momentos, de lembrar que um quadro meu est\u00e1 pendurado em uma das paredes do castelo de Pierre Cardin.","breadcrumb":{"@id":"https:\/\/arte351.pt\/art\/2021\/01\/01\/morre-aos-98-anos-o-estilista-frances-pierre-cardin\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arte351.pt\/art\/2021\/01\/01\/morre-aos-98-anos-o-estilista-frances-pierre-cardin\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/arte351.pt\/art\/2021\/01\/01\/morre-aos-98-anos-o-estilista-frances-pierre-cardin\/#primaryimage","url":"https:\/\/arte351.pt\/art\/wp-content\/uploads\/2021\/01\/arte351-2020-pierre-cardin.jpg","contentUrl":"https:\/\/arte351.pt\/art\/wp-content\/uploads\/2021\/01\/arte351-2020-pierre-cardin.jpg","width":1200,"height":578},{"@type":"BreadcrumbList","@id":"https:\/\/arte351.pt\/art\/2021\/01\/01\/morre-aos-98-anos-o-estilista-frances-pierre-cardin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/arte351.pt\/art\/"},{"@type":"ListItem","position":2,"name":"Morre aos 98 anos o estilista franc\u00eas Pierre Cardin"}]},{"@type":"WebSite","@id":"https:\/\/arte351.pt\/art\/#website","url":"https:\/\/arte351.pt\/art\/","name":"Arte351 - Art Magazine Portugal","description":"","publisher":{"@id":"https:\/\/arte351.pt\/art\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arte351.pt\/art\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/arte351.pt\/art\/#organization","name":"Arte351 - Art Magazine Portugal","url":"https:\/\/arte351.pt\/art\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/arte351.pt\/art\/#\/schema\/logo\/image\/","url":"https:\/\/arte351.pt\/art\/wp-content\/uploads\/2020\/03\/cropped-logo-arte351-color.png","contentUrl":"https:\/\/arte351.pt\/art\/wp-content\/uploads\/2020\/03\/cropped-logo-arte351-color.png","width":514,"height":200,"caption":"Arte351 - Art Magazine Portugal"},"image":{"@id":"https:\/\/arte351.pt\/art\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/arte351magazine\/"]},{"@type":"Person","@id":"https:\/\/arte351.pt\/art\/#\/schema\/person\/1d081d5dbc7c2a3f2317da95c823a5bd","name":"Equipa Arte 351","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3f97e62c832ede8fafe5d2f9e31f8a055e187b6b31056d1e065d95e034db52e2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3f97e62c832ede8fafe5d2f9e31f8a055e187b6b31056d1e065d95e034db52e2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3f97e62c832ede8fafe5d2f9e31f8a055e187b6b31056d1e065d95e034db52e2?s=96&d=mm&r=g","caption":"Equipa Arte 351"},"url":"https:\/\/arte351.pt\/art\/author\/admin2\/"}]}},"_links":{"self":[{"href":"https:\/\/arte351.pt\/art\/wp-json\/wp\/v2\/posts\/4357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arte351.pt\/art\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arte351.pt\/art\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arte351.pt\/art\/wp-json\/wp\/v2\/users\/34415"}],"replies":[{"embeddable":true,"href":"https:\/\/arte351.pt\/art\/wp-json\/wp\/v2\/comments?post=4357"}],"version-history":[{"count":9,"href":"https:\/\/arte351.pt\/art\/wp-json\/wp\/v2\/posts\/4357\/revisions"}],"predecessor-version":[{"id":4390,"href":"https:\/\/arte351.pt\/art\/wp-json\/wp\/v2\/posts\/4357\/revisions\/4390"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arte351.pt\/art\/wp-json\/wp\/v2\/media\/4364"}],"wp:attachment":[{"href":"https:\/\/arte351.pt\/art\/wp-json\/wp\/v2\/media?parent=4357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arte351.pt\/art\/wp-json\/wp\/v2\/categories?post=4357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arte351.pt\/art\/wp-json\/wp\/v2\/tags?post=4357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}